{"id":12397,"date":"2018-12-11T11:43:18","date_gmt":"2018-12-11T10:43:18","guid":{"rendered":"https:\/\/www.textilwaren24.eu\/magazin\/?p=12397"},"modified":"2018-12-11T14:03:46","modified_gmt":"2018-12-11T13:03:46","slug":"gildan-heavy-cotton-t-shirts","status":"publish","type":"post","link":"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/","title":{"rendered":"Gildan Heavy Cotton T-Shirts"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_77 ez-toc-wrap-center counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Inhaltsverzeichnis<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/#%C2%AB_Freizeitmode_aus_feiner_Baumwolle_%C2%BB\" >\u00ab Freizeitmode aus feiner Baumwolle \u00bb<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/#Ein_Blick_in_die_Geschichte\" >Ein Blick in die Geschichte<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/#Unkomplizierte_Basics_werden_zu_Bestsellern\" >Unkomplizierte Basics werden zu Bestsellern<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/#Nachhaltiges_Wirtschaften_und_hoher_ethischer_Anspruch\" >Nachhaltiges Wirtschaften und hoher ethischer Anspruch<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/#T-Shirts_aus_Heavy_Cotton_Farbenfrohe_Freizeitmode_in_hervorragender_Qualitaet\" >T-Shirts aus Heavy Cotton: Farbenfrohe Freizeitmode in hervorragender Qualit\u00e4t<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/#Es_gibt_viele_Gruende_Gildan_T-Shirts_aus_Heavy_Cotton_zu_kaufen\" >Es gibt viele Gr\u00fcnde, Gildan T-Shirts aus Heavy Cotton zu kaufen<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%C2%AB_Freizeitmode_aus_feiner_Baumwolle_%C2%BB\"><\/span>\u00ab Freizeitmode aus feiner Baumwolle \u00bb<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\"><strong>Bequeme Freizeitkleidung aus hochwertigen Materialien, hoher Tragekomfort und \u00e4u\u00dfert zeitlose, aber dennoch moderne Styles. Daf\u00fcr steht der Name <a href=\"https:\/\/www.textilwaren24.eu\/gildan\/\">Gildan<\/a>. Doch wie werden die Produkte der kanadischen Firma gefertigt, welche Unternehmens-Philosophie steht dahinter und wie waren die Anf\u00e4nge des Konzerns? Wir haben uns Gildan n\u00e4her angeschaut.<\/strong><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Ein_Blick_in_die_Geschichte\"><\/span>Ein Blick in die Geschichte<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">Gildan ist eine kanadische Textilmarke, die auf eine lange Vergangenheit zur\u00fcckblicken kann: Bereits 1946 gr\u00fcndete Joseph Chamandy eine Textilfabrik unter dem Namen Harley Inc., die sich auf Tricotage Produkte wie Freizeitmode, Kindermode und Schlafanz\u00fcge spezialisiert hatte. Die Familie Chamandy akquirierte im Laufe der Zeit weitere textilverarbeitende Firmen in der Umgebung von Toronto und firmierte schlie\u00dflich als gro\u00dfes Textilunternehmen 1983 unter dem Namen Gildan. Seit 1984 nun bietet der Textilproduzent qualitativ hochwertige Freizeitkleidung aus Tricotwaren an und hat sich zu einem der gr\u00f6\u00dften vollstufigen Bekleidungshersteller der Welt entwickelt.<\/p>\n<p><a href=\"https:\/\/www.textilwaren24.eu\/gildan\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-12418 size-full\" style=\"text-align: justify;\" title=\"Produkte von Gildan\" src=\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/gildan.jpg\" alt=\"gildan\" width=\"70\" height=\"46\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Der kontinuierlich steigende Umsatz f\u00fchrte schlie\u00dflich zu einem erfolgreichen B\u00f6rsengang im Jahre 1998. Mittlerweile besch\u00e4ftigt das gigantische Unternehmen weltweit 50.000 Mitarbeiter.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Unkomplizierte_Basics_werden_zu_Bestsellern\"><\/span>Unkomplizierte Basics werden zu Bestsellern<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">Die Produkte, die das kanadische Label seit vielen Jahrzehnten weltweit vertreibt, sind denkbar unkompliziert:<\/p>\n<p style=\"text-align: justify;\">Es handelt sich um schlichte <a href=\"https:\/\/www.textilwaren24.eu\/t-shirts\">Basic T-Shirts<\/a>, <a href=\"https:\/\/www.textilwaren24.eu\/poloshirts\">Poloshirts<\/a>, <a href=\"https:\/\/www.textilwaren24.eu\/sweat-shirts\">Sweatshirts<\/a> und <a href=\"https:\/\/www.textilwaren24.eu\/unterwaesche\">Socken<\/a> f\u00fcr die ganze Familie, die durch Druckverfahren oder Stickereien im Nachhinein veredelt werden. Zum gro\u00dfen Erfolg, insbesondere bei Gro\u00dfh\u00e4ndlern auf der ganzen Welt, haben die ausgereiften Schnitte, die riesige Farbauswahl und nicht zuletzt der hohe Qualit\u00e4tsstandard der Marke verholfen. Auf die Freizeitmode der Kanadier ist einfach Verlass!<\/p>\n<figure id=\"attachment_12425\" aria-describedby=\"caption-attachment-12425\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12425 size-full\" title=\"Unkomplizierte Basics werden zu Bestsellern\" src=\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Unkomplizierte-Basics-werden-zu-Bestsellern.jpg\" alt=\"Unkomplizierte Basics werden zu Bestsellern\" width=\"600\" height=\"480\" srcset=\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Unkomplizierte-Basics-werden-zu-Bestsellern.jpg 600w, https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Unkomplizierte-Basics-werden-zu-Bestsellern-300x240.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-12425\" class=\"wp-caption-text\">\u00a9 Fitz \/ Fotolia.com<\/figcaption><\/figure>\n<h2><span class=\"ez-toc-section\" id=\"Nachhaltiges_Wirtschaften_und_hoher_ethischer_Anspruch\"><\/span>Nachhaltiges Wirtschaften und hoher ethischer Anspruch<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">Als vollstufiges Unternehmen hat der Textilproduzent Einfluss auf jede Stufe im Fertigungsprozess. So kann das Unternehmen effizient arbeiten und Ressourcen einsparen, wenn n\u00f6tig. Davon profitieren selbstverst\u00e4ndlich die Handelspartner des Unternehmens: Sie erhalten beste Qualit\u00e4tsprodukte zu unschlagbaren Preisen. Die Unternehmensf\u00fchrung der b\u00f6rsennotierten Textilfirma hat die Vision, permanente Verbesserungen in der Produktion durch kontinuierliche Investitionen in neuste Technologien zu erreichen. Gleichzeitig verpflichtete sich das Unternehmen zur Einhaltung hoher ethischer Standards bei allen Gesch\u00e4ftst\u00e4tigkeiten weltweit.<\/p>\n<figure id=\"attachment_12434\" aria-describedby=\"caption-attachment-12434\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12434 size-full\" title=\"Nachhaltiges Wirtschaften und hoher ethischer Anspruch\" src=\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Nachhaltiges-Wirtschaften-und-hoher-ethischer-Anspruch.jpg\" alt=\"Nachhaltiges Wirtschaften und hoher ethischer Anspruch\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Nachhaltiges-Wirtschaften-und-hoher-ethischer-Anspruch.jpg 600w, https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Nachhaltiges-Wirtschaften-und-hoher-ethischer-Anspruch-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-12434\" class=\"wp-caption-text\">\u00a9 4Max \/ Fotolia.com<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">2016 hat der Verwaltungsrat einen aktualisierten Verhaltenskodex verabschiedet, der f\u00fcr alle Direktoren, leitenden Angestellten und Mitarbeiter gilt und integres Verhalten gegen\u00fcber Kollegen, Kunden, Lieferanten und anderen Gesch\u00e4ftspartnern beschreibt und einfordert. Der Ethikkodex befasst sich beispielsweise mit Fragen zu den Themen Menschenrechte, Gesundheit und Sicherheit, Antikorruption und Insiderhandel. Ebenso werden alle Mitarbeiter in F\u00fchrungspositionen j\u00e4hrlich einem Zertifizierungsprozess unterzogen. Jeder neue Kollege wird verpflichtet, den Ethikkodex w\u00e4hrend seiner Ausbildung zu lesen und zu unterschreiben.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Kunden, die sich Nachhaltigkeit auf die Fahne geschrieben haben, k\u00f6nnen also ganz entspannt die Orderb\u00fccher f\u00fcllen: Das b\u00f6rsennotierte Unternehmen hat seine Hausaufgaben gemacht.<\/p>\n<\/blockquote>\n<h2><span class=\"ez-toc-section\" id=\"T-Shirts_aus_Heavy_Cotton_Farbenfrohe_Freizeitmode_in_hervorragender_Qualitaet\"><\/span>T-Shirts aus Heavy Cotton: Farbenfrohe Freizeitmode in hervorragender Qualit\u00e4t<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">Das kanadische Label fertigt Wirkwaren in verschiedenen Gewichtsklassen f\u00fcr die ganze Familie und f\u00fcr viele Trageanl\u00e4sse. Jeder, der auf der Suche nach hochwertiger Freizeitmode f\u00fcr Damen, Herren und Kinder ist, wird irgendwann auf die Marke sto\u00dfen.<\/p>\n<p><a href=\"https:\/\/www.textilwaren24.eu\/kinderbekleidung\/kinderbekleidung-baby-wear\/g5100p-gildan-heavy-cotton-toddler-t-shirt\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12401 size-full\" title=\"Gildan: Heavy Cotton Toddler T-Shirt | 100% Baumwolle (Sport Grey: 90% Baumwolle \/ 10% Polyester)\" src=\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/gildan-heavy-cotton-toddler-t-shirt.jpg\" alt=\"gildan-heavy-cotton-toddler-t-shirt\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/gildan-heavy-cotton-toddler-t-shirt.jpg 600w, https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/gildan-heavy-cotton-toddler-t-shirt-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">F\u00fcr seine kombistarken Shirt-Kollektionen verwendet der erfahrene Textilhersteller aus Kanada verschiedene Baumwollqualit\u00e4ten in unterschiedlichen Mischungsverh\u00e4ltnissen und Grammaturen. Herausragend ist die au\u00dfergew\u00f6hnliche Farbpalette, in der die tragbaren Basicshirts, Hoodies und sogar Unterw\u00e4sche angeboten werden.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Ob klassisch oder hochmodisch eingef\u00e4rbt: F\u00fcr jeden Geschmack ist in der Kollektion etwas dabei.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Die Materialmischungen reichen von leichten Baumwoll- Polyestergemischen bis hin zu schwerer, reiner Baumwolle, der sogenannten &#8222;Heavy Cotton&#8220;. Die erfolgreichen Gildan Heavy Cotton T-Shirt-Linie f\u00fcr Damen, Herren und Kinder zum Beispiel werden aus einer Schlauchware in reiner Baumwolle mit der Gewichtsklasse um 180 g\/m2 gefertigt. Sie entwickelten sich zu Bestsellern und wurden weltweit bereits millionenfach verkauft.<\/p>\n<p><a href=\"https:\/\/www.textilwaren24.eu\/kinderbekleidung\/kinderbekleidung-kids-t-shirts\/g5000k-gildan-heavy-cotton-youth-t-shirt\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12404 size-full\" title=\"Gildan: Heavy Cotton Youth T- Shirt | 100% Baumwolle (Ash Grey: 99% Baumwolle \/ 1% Polyester; Sport Grey: 90% Baumwolle \/ 10% Polyester; Graphite Heather: 50% Baumwolle \/ 50% Polyester)\" src=\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/gildan-heavy-cotton-youth-t-shirt.jpg\" alt=\"gildan-heavy-cotton-youth-t-shirt\" width=\"600\" height=\"540\" srcset=\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/gildan-heavy-cotton-youth-t-shirt.jpg 600w, https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/gildan-heavy-cotton-youth-t-shirt-300x270.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Das Erfolgsgeheimnis: Der vorgewaschene Jersey aus reiner Baumwolle hat den Wohlf\u00fchl-Effekt und l\u00e4uft garantiert nicht mehr ein. Doppeln\u00e4hte an den \u00c4rmeln und am Saum sorgen f\u00fcr Stabilit\u00e4t, der Schulterbereich eines Gildan Heavy Cotton Oberteils ist mit einem durchgehenden Schulterband gesichert. Viele Kunden werden es zu sch\u00e4tzen wissen, dass das eingen\u00e4hte Label so perforiert wurde, dass es ganz einfach abgetrennt werden kann. Es ist nicht n\u00f6tig, eine Schere daf\u00fcr zu benutzen.<\/p>\n<figure id=\"attachment_12423\" aria-describedby=\"caption-attachment-12423\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12423 size-full\" title=\"Mann im wei\u00dfen T-Shirt\" src=\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Mann-im-weissen-T-Shirt.jpg\" alt=\"Mann im weissen T-Shirt\" width=\"600\" height=\"401\" srcset=\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Mann-im-weissen-T-Shirt.jpg 600w, https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Mann-im-weissen-T-Shirt-300x201.jpg 300w, https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Mann-im-weissen-T-Shirt-110x75.jpg 110w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-12423\" class=\"wp-caption-text\">\u00a9 rh2010 \/ Fotolia.com<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Ein weiterer Grund f\u00fcr die gro\u00dfe Nachfrage nach den Gildan Heavy Cotton Artikeln ist der Gr\u00f6\u00dfenlauf, der bei vielen Farben von S bis 5XL reicht. Die Kunden haben nur noch die Aufgabe, aus der bis zu 50 Farben gro\u00dfen Auswahl ihren Favoriten auszuw\u00e4hlen. Haben Sie Ihre Lieblingsfarbe schon gefunden?<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Es_gibt_viele_Gruende_Gildan_T-Shirts_aus_Heavy_Cotton_zu_kaufen\"><\/span>Es gibt viele Gr\u00fcnde, Gildan T-Shirts aus Heavy Cotton zu kaufen<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align: justify;\">Kleidungsst\u00fccke aus Baumwolle haben viele positive Eigenschaften. Sie tragen sich angenehm auf der Haut, sind formstabil und nehmen Feuchtigkeit gut auf. Auf der glatten Oberfl\u00e4che hochwertiger, langstapeliger Baumwollgewirke kommen Textildrucke und Stickereien besonders sch\u00f6n zur Geltung. Ein Gildan Heavy Cotton Shirt ist aus besonders dichter Baumwolle gestrickt, die ein Fl\u00e4chengewicht von ca. 180 g\/m2 aufweist. Das Gewicht kann \u00fcbrigens je nach Farbton geringf\u00fcgig abweichen.<\/p>\n<p><a href=\"https:\/\/www.textilwaren24.eu\/t-shirts\/basic-t-shirts-fuer-sie-und-ihn\/basic-t-shirts-fuer-sie-ihn-basic\/g5000-gildan-heavy-cotton-t-shirt\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12411 size-full\" title=\"Gildan: Heavy Cotton T- Shirt | 100% Baumwolle (Ash Grey: 99% Baumwolle \/ 1% Polyester; Antique Cherry Red, Antique Irish Green, Antique Jade Dome, Antique Orange, Antique Sapphire, Sport Grey: 90% Baumwolle \/ 10 % Polyester; Blackberry, Dark Heather, Lilac, Midnight, Russet, Sunset, Tweed, Heather Sapphire, Safety Pink, Graphite Heather: 50% Baumwolle \/ 50% Polyester)\" src=\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/gildan-heavy-cotton-t-shirt.jpg\" alt=\"gildan-heavy-cotton-t-shirt\" width=\"600\" height=\"580\" srcset=\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/gildan-heavy-cotton-t-shirt.jpg 600w, https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/gildan-heavy-cotton-t-shirt-300x290.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Gildan T-Shirts aus Heavy Cotton lassen sich aufgrund der gro\u00dfen Farbpalette hervorragend zu modernen oder klassischen Outfits kombinieren. Ein Hoodie oder T-Shirt aus der Herrenkollektion passt hervorragend zur angesagten Jeans , sieht aber auch unter einem modern geschnittenen Blazer oder einem gepflegten Cardigan ansprechend aus.<\/p>\n<p><a href=\"https:\/\/www.textilwaren24.eu\/t-shirts\/basic-t-shirts-fuer-sie-und-ihn\/basic-t-shirts-fuer-sie-ihn-basic\/g5000l-gildan-heavy-cotton-ladies-t-shirt\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12407 size-full\" title=\"Gildan: Heavy Cotton Ladies T-Shirt | 100% Baumwolle (Sport Grey: 90% Baumwolle \/ 10% Polyester; Dark Heather, Heather Sapphire, Lilac, Sunset, Safety Pink, Graphite Heather: 50% Baumwolle \/ 50% Polyester)\" src=\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/gildan-heavy-cotton-ladies-t-shirt.jpg\" alt=\"gildan-heavy-cotton-ladies-t-shirt\" width=\"600\" height=\"500\" srcset=\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/gildan-heavy-cotton-ladies-t-shirt.jpg 600w, https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/gildan-heavy-cotton-ladies-t-shirt-300x250.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Ob im Fitness-Studio oder beim Yoga: Damen machen eine gute Figur in den feminin geschnittenen Shirts. Bei der gro\u00dfen Farbauswahl und dem g\u00fcnstigen Preis f\u00e4llt es nicht schwer, gleich mehrere Tops zu kaufen und diese zum Beispiel im Lagenlook unter einem Kapuzensweatshirt in Heavy Cotton zu tragen.<\/p>\n<figure id=\"attachment_12430\" aria-describedby=\"caption-attachment-12430\" style=\"width: 600px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-12430 size-full\" title=\"Feminin geschnittene Shirts beim Sport\" src=\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Feminin-geschnittene-Shirts-beim-Sport.jpg\" alt=\"Feminin geschnittene Shirts beim Sport\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Feminin-geschnittene-Shirts-beim-Sport.jpg 600w, https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Feminin-geschnittene-Shirts-beim-Sport-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption id=\"caption-attachment-12430\" class=\"wp-caption-text\">\u00a9 Daria \/ Fotolia.com<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Wer einmal von der verl\u00e4sslichen Qualit\u00e4t der Gildan Shirts \u00fcberzeugt ist, wird gewiss zum Wiederholungsk\u00e4ufer. Kennen Sie bereits die Unterw\u00e4sche oder die Sockenkollektion der Weltmarke aus Kanada?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab Freizeitmode aus feiner Baumwolle \u00bb Bequeme Freizeitkleidung aus hochwertigen Materialien, hoher Tragekomfort und \u00e4u\u00dfert zeitlose, aber dennoch moderne Styles. Daf\u00fcr steht der Name Gildan. Doch wie werden die Produkte der kanadischen Firma gefertigt, welche Unternehmens-Philosophie steht dahinter und wie waren die Anf\u00e4nge des Konzerns? Wir haben uns Gildan n\u00e4her angeschaut. Ein Blick in die &hellip;<\/p>\n","protected":false},"author":2,"featured_media":12433,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[30,673,177,128,869,870,173,131,27],"class_list":["post-12397","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fashion","tag-basics","tag-baumwolle","tag-damenmode","tag-freizeitmode","tag-gildan","tag-heavy-cotton","tag-herrenmode","tag-kindermode","tag-t-shirts"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gildan Heavy Cotton T-Shirts - Textilwaren Magazin<\/title>\n<meta name=\"description\" content=\"Entdecken Sie die zeitlose Basic-Fashion Mode des kanadischen Labels Gildan \u2713 Das Textilwaren Magazin stellt die Firma und seine sch\u00f6nsten St\u00fccke vor \u2713\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gildan Heavy Cotton T-Shirts - Textilwaren Magazin\" \/>\n<meta property=\"og:description\" content=\"Entdecken Sie die zeitlose Basic-Fashion Mode des kanadischen Labels Gildan \u2713 Das Textilwaren Magazin stellt die Firma und seine sch\u00f6nsten St\u00fccke vor \u2713\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/\" \/>\n<meta property=\"og:site_name\" content=\"Textilwaren Magazin\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-11T10:43:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-12-11T13:03:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Gildan-Heavy-Cotton-T-Shirts.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/\",\"url\":\"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/\",\"name\":\"Gildan Heavy Cotton T-Shirts - Textilwaren Magazin\",\"isPartOf\":{\"@id\":\"https:\/\/www.textilwaren24.eu\/magazin\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Gildan-Heavy-Cotton-T-Shirts.jpg\",\"datePublished\":\"2018-12-11T10:43:18+00:00\",\"dateModified\":\"2018-12-11T13:03:46+00:00\",\"author\":{\"@id\":\"https:\/\/www.textilwaren24.eu\/magazin\/#\/schema\/person\/9c4e510f1296cc7c4a90e209f49f38b4\"},\"description\":\"Entdecken Sie die zeitlose Basic-Fashion Mode des kanadischen Labels Gildan \u2713 Das Textilwaren Magazin stellt die Firma und seine sch\u00f6nsten St\u00fccke vor \u2713\",\"breadcrumb\":{\"@id\":\"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/#primaryimage\",\"url\":\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Gildan-Heavy-Cotton-T-Shirts.jpg\",\"contentUrl\":\"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Gildan-Heavy-Cotton-T-Shirts.jpg\",\"width\":800,\"height\":533,\"caption\":\"\u00a9 Alena Ozerova \/ Fotolia.com\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.textilwaren24.eu\/magazin\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gildan Heavy Cotton T-Shirts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.textilwaren24.eu\/magazin\/#website\",\"url\":\"https:\/\/www.textilwaren24.eu\/magazin\/\",\"name\":\"Textilwaren Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.textilwaren24.eu\/magazin\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.textilwaren24.eu\/magazin\/#\/schema\/person\/9c4e510f1296cc7c4a90e209f49f38b4\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.textilwaren24.eu\/magazin\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a794a4fe8a9b9c52241597eb381dfa2e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a794a4fe8a9b9c52241597eb381dfa2e?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gildan Heavy Cotton T-Shirts - Textilwaren Magazin","description":"Entdecken Sie die zeitlose Basic-Fashion Mode des kanadischen Labels Gildan \u2713 Das Textilwaren Magazin stellt die Firma und seine sch\u00f6nsten St\u00fccke vor \u2713","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/","og_locale":"de_DE","og_type":"article","og_title":"Gildan Heavy Cotton T-Shirts - Textilwaren Magazin","og_description":"Entdecken Sie die zeitlose Basic-Fashion Mode des kanadischen Labels Gildan \u2713 Das Textilwaren Magazin stellt die Firma und seine sch\u00f6nsten St\u00fccke vor \u2713","og_url":"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/","og_site_name":"Textilwaren Magazin","article_published_time":"2018-12-11T10:43:18+00:00","article_modified_time":"2018-12-11T13:03:46+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Gildan-Heavy-Cotton-T-Shirts.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/","url":"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/","name":"Gildan Heavy Cotton T-Shirts - Textilwaren Magazin","isPartOf":{"@id":"https:\/\/www.textilwaren24.eu\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/#primaryimage"},"image":{"@id":"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/#primaryimage"},"thumbnailUrl":"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Gildan-Heavy-Cotton-T-Shirts.jpg","datePublished":"2018-12-11T10:43:18+00:00","dateModified":"2018-12-11T13:03:46+00:00","author":{"@id":"https:\/\/www.textilwaren24.eu\/magazin\/#\/schema\/person\/9c4e510f1296cc7c4a90e209f49f38b4"},"description":"Entdecken Sie die zeitlose Basic-Fashion Mode des kanadischen Labels Gildan \u2713 Das Textilwaren Magazin stellt die Firma und seine sch\u00f6nsten St\u00fccke vor \u2713","breadcrumb":{"@id":"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/#primaryimage","url":"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Gildan-Heavy-Cotton-T-Shirts.jpg","contentUrl":"https:\/\/www.textilwaren24.eu\/magazin\/wp-content\/uploads\/2019\/12\/Gildan-Heavy-Cotton-T-Shirts.jpg","width":800,"height":533,"caption":"\u00a9 Alena Ozerova \/ Fotolia.com"},{"@type":"BreadcrumbList","@id":"https:\/\/www.textilwaren24.eu\/magazin\/gildan-heavy-cotton-t-shirts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.textilwaren24.eu\/magazin\/"},{"@type":"ListItem","position":2,"name":"Gildan Heavy Cotton T-Shirts"}]},{"@type":"WebSite","@id":"https:\/\/www.textilwaren24.eu\/magazin\/#website","url":"https:\/\/www.textilwaren24.eu\/magazin\/","name":"Textilwaren Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.textilwaren24.eu\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.textilwaren24.eu\/magazin\/#\/schema\/person\/9c4e510f1296cc7c4a90e209f49f38b4","name":"admin","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.textilwaren24.eu\/magazin\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a794a4fe8a9b9c52241597eb381dfa2e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a794a4fe8a9b9c52241597eb381dfa2e?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.textilwaren24.eu\/magazin\/wp-json\/wp\/v2\/posts\/12397"}],"collection":[{"href":"https:\/\/www.textilwaren24.eu\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.textilwaren24.eu\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.textilwaren24.eu\/magazin\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.textilwaren24.eu\/magazin\/wp-json\/wp\/v2\/comments?post=12397"}],"version-history":[{"count":28,"href":"https:\/\/www.textilwaren24.eu\/magazin\/wp-json\/wp\/v2\/posts\/12397\/revisions"}],"predecessor-version":[{"id":12435,"href":"https:\/\/www.textilwaren24.eu\/magazin\/wp-json\/wp\/v2\/posts\/12397\/revisions\/12435"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.textilwaren24.eu\/magazin\/wp-json\/wp\/v2\/media\/12433"}],"wp:attachment":[{"href":"https:\/\/www.textilwaren24.eu\/magazin\/wp-json\/wp\/v2\/media?parent=12397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.textilwaren24.eu\/magazin\/wp-json\/wp\/v2\/categories?post=12397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.textilwaren24.eu\/magazin\/wp-json\/wp\/v2\/tags?post=12397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}