{"id":1259,"count":1,"description":"","link":"https:\/\/www.textilwaren24.eu\/magazin\/tag\/fleecepullover\/","name":"Fleecepullover","slug":"fleecepullover","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Fleecepullover&quot; Tag - Textilwaren Magazin<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Fleecepullover&quot; Tag - Textilwaren Magazin\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.textilwaren24.eu\/magazin\/tag\/fleecepullover\/\" \/>\n<meta property=\"og:site_name\" content=\"Textilwaren Magazin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.textilwaren24.eu\/magazin\/tag\/fleecepullover\/\",\"url\":\"https:\/\/www.textilwaren24.eu\/magazin\/tag\/fleecepullover\/\",\"name\":\"\\\"Fleecepullover\\\" Tag - Textilwaren Magazin\",\"isPartOf\":{\"@id\":\"https:\/\/www.textilwaren24.eu\/magazin\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.textilwaren24.eu\/magazin\/tag\/fleecepullover\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.textilwaren24.eu\/magazin\/tag\/fleecepullover\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.textilwaren24.eu\/magazin\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fleecepullover\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.textilwaren24.eu\/magazin\/#website\",\"url\":\"https:\/\/www.textilwaren24.eu\/magazin\/\",\"name\":\"Textilwaren Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.textilwaren24.eu\/magazin\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Fleecepullover\" Tag - Textilwaren Magazin","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"\"Fleecepullover\" Tag - Textilwaren Magazin","og_url":"https:\/\/www.textilwaren24.eu\/magazin\/tag\/fleecepullover\/","og_site_name":"Textilwaren Magazin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.textilwaren24.eu\/magazin\/tag\/fleecepullover\/","url":"https:\/\/www.textilwaren24.eu\/magazin\/tag\/fleecepullover\/","name":"\"Fleecepullover\" Tag - Textilwaren Magazin","isPartOf":{"@id":"https:\/\/www.textilwaren24.eu\/magazin\/#website"},"breadcrumb":{"@id":"https:\/\/www.textilwaren24.eu\/magazin\/tag\/fleecepullover\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.textilwaren24.eu\/magazin\/tag\/fleecepullover\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.textilwaren24.eu\/magazin\/"},{"@type":"ListItem","position":2,"name":"Fleecepullover"}]},{"@type":"WebSite","@id":"https:\/\/www.textilwaren24.eu\/magazin\/#website","url":"https:\/\/www.textilwaren24.eu\/magazin\/","name":"Textilwaren Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.textilwaren24.eu\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.textilwaren24.eu\/magazin\/wp-json\/wp\/v2\/tags\/1259"}],"collection":[{"href":"https:\/\/www.textilwaren24.eu\/magazin\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.textilwaren24.eu\/magazin\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.textilwaren24.eu\/magazin\/wp-json\/wp\/v2\/posts?tags=1259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}